{"id":12125,"date":"2023-11-09T08:40:31","date_gmt":"2023-11-09T13:40:31","guid":{"rendered":"https:\/\/www.sail.ca\/blog\/10-marques-achat-local-a-offrir-en-cadeau\/"},"modified":"2024-03-25T08:27:38","modified_gmt":"2024-03-25T13:27:38","slug":"10-marques-achat-local-a-offrir-en-cadeau","status":"publish","type":"post","link":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/","title":{"rendered":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pourquoi ne pas offrir un article de plein air sign\u00e9 par une marque qu\u00e9b\u00e9coise? En plus d\u2019encourager l\u2019achat local et les d\u00e9taillants qu\u00e9b\u00e9cois et canadiens, vous trouverez assur\u00e9ment le cadeau id\u00e9al, car ce n\u2019est pas la vari\u00e9t\u00e9 d\u2019id\u00e9es-cadeaux pour femmes, pour hommes ou pour enfants qui manquent!<\/p>\n","protected":false},"author":9,"featured_media":19265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[161],"tags":[1368,1664],"class_list":["post-12125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marques","tag-idees-cadeaux","tag-cadeaux"],"acf":{"post_flexible_content":[{"acf_fc_layout":"text_content","content_anchor":false,"anchor_link_text":"","text_content":"<strong>Pourquoi ne pas offrir un article de plein air sign\u00e9 par une marque qu\u00e9b\u00e9coise? En plus d\u2019encourager l\u2019achat local et les d\u00e9taillants qu\u00e9b\u00e9cois et canadiens, vous trouverez assur\u00e9ment le cadeau id\u00e9al, car ce n\u2019est pas la vari\u00e9t\u00e9 d\u2019id\u00e9es-cadeaux pour femmes, pour hommes ou pour enfants qui manquent!<\/strong>\r\n\r\n&nbsp;"},{"acf_fc_layout":"content_anchors_list","anchors_section_title":"Survolez les caract\u00e9ristiques des 10 marques d\u2019ici et trouvez un cadeau qui plaira assur\u00e9ment \u00e0 votre adepte de plein air pr\u00e9f\u00e9r\u00e9(e)."},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Tentree","text_content":"<h2>Pourquoi favoriser l\u2019achat local?<\/h2>\r\n<span style=\"font-weight: 400;\">Cela permet non seulement d\u2019encourager les cr\u00e9ateurs d\u2019ici ainsi que les <\/span><span style=\"font-weight: 400;\">compagnies qu\u00e9b\u00e9coises et canadiennes<\/span><span style=\"font-weight: 400;\">, mais <\/span><span style=\"font-weight: 400;\">aussi <\/span><span style=\"font-weight: 400;\">de <\/span><span style=\"font-weight: 400;\">participer \u00e0 la r\u00e9duction des<\/span><span style=\"font-weight: 400;\"> \u00e9missions de <\/span><span style=\"font-weight: 400;\">CO<\/span><span style=\"font-weight: 400;\">2<\/span><span style=\"font-weight: 400;\"> li\u00e9es au transport de marchandises. Une bonne fa\u00e7on d\u2019aider la plan\u00e8te en m\u00eame temps que nos marques locales!<\/span>\r\n\r\n<span style=\"font-weight: 400;\">Que vous vouliez remercier une personne importante <\/span><span style=\"font-weight: 400;\">de votre entourage <\/span><span style=\"font-weight: 400;\">ou souhaitiez faire plaisir aux gens qui comptent pour vous, un pr\u00e9sent significatif est toujours de mise. Nous avons donc <\/span><span style=\"font-weight: 400;\">pr\u00e9par\u00e9 une liste <\/span><span style=\"font-weight: 400;\">de marques <\/span><span style=\"font-weight: 400;\">locales qui sauront vous inspirer afin de vous aider \u00e0 <\/span><span style=\"font-weight: 400;\">trouver LES meilleures id\u00e9es de cadeaux!<\/span>\r\n\r\n<span style=\"font-weight: 400;\">D\u00e9couvrez nos suggestions.<\/span>\r\n<h2>Achat local : 10 marques de plein air d\u2019ici \u00e0 offrir en cadeau<\/h2>\r\n<h3>1. Un achat local durable avec Tentree<\/h3>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/tentree\"><img class=\"aligncenter wp-image-8766 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Tentree-marque-locale.jpg\" alt=\"Marque locale Tentree\" width=\"550\" height=\"850\" \/><\/a>\r\nCamp\u00e9e \u00e0 Vancouver, la marque <a href=\"https:\/\/www.sail.ca\/fr\/tentree\" target=\"_blank\" rel=\"noopener\">Tentree<\/a> propose des accessoires et des v\u00eatements hyper confortables pour homme et pour femme. Id\u00e9al pour les moments de d\u00e9tente au chalet ou pour superposer \u00e0 un manteau chaud lors d\u2019une promenade sous la neige! En plus, les pi\u00e8ces sont con\u00e7ues de mani\u00e8re \u00e9coresponsable et la marque s\u2019engage \u00e0 planter 10 arbres pour chaque article vendu. Le plus dur sera de choisir quoi offrir entre une veste \u00e0 capuchon ou un pantalon en Lyocell Tencel\u2122!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_tentree"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"FIG","text_content":"<h3>2. Une escapade styl\u00e9e avec FIG<\/h3>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/fig\"><img class=\"aligncenter wp-image-8759 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/FIG-marque-locale.jpg\" alt=\"Marque locale FIG\" width=\"550\" height=\"850\" \/><\/a>Envie de faire plaisir \u00e0 une globe-trotteuse qui adore voyager, que ce soit en sol canadien ou \u00e0 l\u2019\u00e9tranger? Peu importe sa prochaine destination, il y aura toujours de la place dans ses bagages pour un v\u00eatement confortable, polyvalent et \u00e9l\u00e9gant. Offrez-lui <a href=\"https:\/\/www.sail.ca\/fr\/fig\" target=\"_blank\" rel=\"noopener\">une pi\u00e8ce de FIG<\/a>, une marque pens\u00e9e pour les aventuri\u00e8res qui aiment bouger et s\u2019\u00e9vader avec style!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_fig"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Quartz Co.","text_content":"<h3>3. L\u2019atteinte de nouveaux sommets avec Quartz Co.<\/h3>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/quartz-co\"><img class=\"aligncenter wp-image-8764 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Quartz-marque-locale.jpg\" alt=\"Marque locale Quartz Co.\" width=\"550\" height=\"850\" \/><\/a>Allier allure sophistiqu\u00e9e et r\u00e9sistance aux intemp\u00e9ries est possible avec la marque montr\u00e9alaise <a href=\"https:\/\/www.sail.ca\/fr\/quartz-co\" target=\"_blank\" rel=\"noopener\">Quartz Co.<\/a>, dirig\u00e9e par trois fr\u00e8res ing\u00e9nieurs de formation. Les manteaux de mi-saison et les manteaux d\u2019hiver sont con\u00e7us pour un style de vie nordique, permettant d\u2019affronter des m\u00e9t\u00e9os glaciales et des rafales sans jamais faire de compromis sur le style. En fouillant parmi ces manteaux faits d\u2019isolants puissants, vous risquez de vouloir vous faire un cadeau \u00e9galement!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_quartz-co"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Hook\u00e9","text_content":"<h3>4. Une journ\u00e9e de p\u00eache in\u00e9gal\u00e9e avec Hook\u00e9<\/h3>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/hooke\"><img class=\"aligncenter wp-image-8760 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Hooke-marque-locale.jpg\" alt=\"Marque locale Hook\u00e9\" width=\"550\" height=\"850\" \/><\/a>De plus en plus pris\u00e9e par les p\u00eacheurs et autres adeptes d\u2019activit\u00e9s en plein air, la marque qu\u00e9b\u00e9coise <a href=\"https:\/\/www.sail.ca\/fr\/hooke\" target=\"_blank\" rel=\"noopener\">Hook\u00e9<\/a> propose des v\u00eatements d\u00e9contract\u00e9s qui font \u00e9cho \u00e0 l\u2019univers de la chasse et de la p\u00eache, tout indiqu\u00e9s pour une vir\u00e9e en chaloupe ou dans une pourvoirie. De quoi \u00e9pater la galerie encore plus que les fameuses histoires de p\u00eache!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_hooke"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Indyeva","text_content":"<h3>5. Une aventure en nature avec Indyeva<\/h3>\r\n<img class=\"aligncenter wp-image-15329\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/manteau_Indyeva.jpg\" alt=\"marques \u00e0 offrir en cadeau Indyeva\" width=\"550\" height=\"850\" \/>Maman, meilleure amie, cousine, belle-fille\u2026 si vous avez dans votre entourage une femme qui carbure \u00e0 l\u2019aventure et s\u2019\u00e9merveille sans cesse devant la beaut\u00e9 de la nature, il y a fort \u00e0 parier qu\u2019elle saura appr\u00e9cier les v\u00eatements de plein air aussi esth\u00e9tiques que pratiques con\u00e7us par la marque qu\u00e9b\u00e9coise <a href=\"https:\/\/www.sail.ca\/fr\/indyeva\" target=\"_blank\" rel=\"noopener\">Indyeva<\/a>. Confortables, styl\u00e9s et bien pens\u00e9s, les v\u00eatements et manteaux Indyeva sont durables et produits de fa\u00e7on \u00e0 avoir un impact minimal sur l\u2019environnement et les \u00eatres vivants. Voil\u00e0 de quoi faire briller les yeux de votre aventuri\u00e8re pr\u00e9f\u00e9r\u00e9e!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_indyeva"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Borealis ","text_content":"<h3>6. Une exp\u00e9dition polaire avec Borealis<\/h3>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/borealis\"><img class=\"aligncenter wp-image-8758 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Borealis-marque-locale.jpg\" alt=\"Marque locale Borealis\" width=\"550\" height=\"850\" \/><\/a>Faites d\u2019une pierre deux coups et offrez un cadeau pratique qui r\u00e9chauffera le c\u0153ur <span style=\"font-weight: 400;\">de celles et ceux qui le d\u00e9balleront \u2013 y compris les minis<\/span>. Nos suggestions : des<a href=\"https:\/\/www.sail.ca\/fr\/borealis\" target=\"_blank\" rel=\"noopener\"> pantoufles duveteuses<\/a>, un <a href=\"https:\/\/www.sail.ca\/fr\/borealis\" target=\"_blank\" rel=\"noopener\">manteau chaud<\/a>, des <a href=\"https:\/\/www.sail.ca\/fr\/borealis\" target=\"_blank\" rel=\"noopener\">bottes bien isol\u00e9e<\/a>s. <span style=\"font-weight: 400;\">Le plus beau dans tout \u00e7a<\/span><span style=\"font-weight: 400;\">?<\/span> Le design est fait \u00e0 Montr\u00e9al et les prix sont tr\u00e8s abordables."},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_borealis"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Pelican","text_content":"<h2 id=\"produit-7\">7. Un saut \u00e0 l\u2019eau avec Pelican<\/h2>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/pelican\"><img class=\"aligncenter wp-image-8763 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Pelican-marque-locale.jpg\" alt=\"Marque locale Pelican\" width=\"550\" height=\"850\" \/><\/a> M\u00eame si la saison froide n\u2019est pas termin\u00e9e, l\u2019\u00e9t\u00e9 n\u2019est jamais bien loin! C\u2019est le moment de prendre de l\u2019avance <span style=\"font-weight: 400;\">en offrant<\/span> un <a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-nautiques\/kayaks\" target=\"_blank\" rel=\"noopener\">kayak<\/a> ou une<a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-nautiques\/planches-a-pagaie\" target=\"_blank\" rel=\"noopener\"> planche \u00e0 pagaie<\/a> aux mordus de <a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-nautiques\" target=\"_blank\" rel=\"noopener\">sports nautiques<\/a> sur votre liste. Un succ\u00e8s assur\u00e9 avec <a href=\"https:\/\/www.sail.ca\/fr\/pelican\" target=\"_blank\" rel=\"noopener\">P\u00e9lican<\/a>, d\u2019autant plus que ces sports n\u2019arr\u00eatent pas de gagner en popularit\u00e9!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_pelican"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Baffin","text_content":"<h2 id=\"produit-8\">8. Une promenade nordique avec Baffin<\/h2>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/baffin\"><img class=\"aligncenter wp-image-8757 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Baffin-marque-locale.jpg\" alt=\"Marque locale Baffin\" width=\"550\" height=\"850\" \/><\/a>Votre tendre moiti\u00e9 poss\u00e8de tout ce dont elle a besoin? Pas tout \u00e0 fait! Il ne manquait qu\u2019une paire de bottes <a href=\"https:\/\/www.sail.ca\/fr\/baffin\" target=\"_blank\" rel=\"noopener\">Baffin<\/a> \u00e0 ajouter \u00e0 son attirail! Le design original est inspir\u00e9 par les chaussures que portait le peuple autochtone de l\u2019\u00eele de Baffin dans les ann\u00e9es 1980. En prime, la marque propose des mod\u00e8les pour enfants qui prot\u00e9geront efficacement les petits pieds du froid. Une belle id\u00e9e de cadeau qui fera plaisir aux parents comme aux tout-petits!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_baffin"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Kombi","text_content":"<h2 id=\"produit-9\">9. Des jeux dans la neige avec Kombi<\/h2>\r\n<a href=\"https:\/\/www.sail.ca\/fr\/kombi\"><img class=\"aligncenter wp-image-8761 size-full\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Kombi-marque-locale.jpg\" alt=\"Marque locale Kombi\" width=\"550\" height=\"850\" \/><\/a>D\u00e9j\u00e0 plus de 60 ans que la marque <a href=\"https:\/\/www.sail.ca\/fr\/kombi\" target=\"_blank\" rel=\"noopener\">Kombi<\/a> vous habille par temps froid! Si la marque est surtout connue pour ses gants et ses mitaines \u00e0 l\u2019\u00e9preuve des froids polaires, elle gagne \u00e0 \u00eatre connue pour ses couches de base en <span style=\"font-weight: 400;\">laine m\u00e9rinos <\/span><span style=\"font-weight: 400;\">et en polyester, <\/span><span style=\"font-weight: 400;\">ultrapratiques<\/span> pour s\u2019adonner au syst\u00e8me multicouche. Parmi la vaste s\u00e9lection allant des passe-montagnes color\u00e9s pour les enfants aux mitaines en cuir pour les femmes, vous trouverez assur\u00e9ment votre compte!"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_kombi"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Kanuk","text_content":"<h2 id=\"produit-10\">10. Des hivers bien au chaud avec Kanuk<\/h2>\r\n<img class=\"wp-image-19253 aligncenter\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/02\/Manteau-Kanuk.jpg\" alt=\"Manteau Kanuk\" width=\"550\" height=\"825\" \/>\r\n\r\nKanuk est c\u00e9l\u00e8bre dans le monde des manteaux d\u2019hiver, et ce n\u2019est pas un hasard. Fabriqu\u00e9s de fa\u00e7on artisanale \u00e0 Montr\u00e9al, les manteaux de la marque qu\u00e9b\u00e9coise sont un gage de qualit\u00e9, de durabilit\u00e9 et de protection in\u00e9gal\u00e9e contre les rigueurs de l\u2019hiver. Que vous l\u2019offriez \u00e0 un \u00eatre cher qui raffole de nos longs hivers, ou bien \u00e0 un proche qui redoute toujours l\u2019arriv\u00e9e de la saison froide, ce cadeau r\u00e9chauffera son c\u0153ur (et son corps!) ann\u00e9e apr\u00e8s ann\u00e9e.\r\n\r\nSi vous \u00eates encore en train de tergiverser \u00e0 propos des id\u00e9es-cadeaux sur lesquelles arr\u00eater votre choix, misez sur la carte-cadeau de SAIL!\r\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">[stag_button url=\"<\/span><span style=\"font-weight: 400;\">https:\/\/www.sail.ca\/fr\/sail-carte-cadeau-valide-en-magasin-et-en-ligne<\/span><span style=\"font-weight: 400;\">\" style=\"black\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Achetez une carte-cadeau[\/stag_button]<\/span><\/p>"},{"acf_fc_layout":"nosto_products","content_anchor":false,"anchor_link_text":"","nosto_class_name":"blog_cp_manteaux-d-hiver_kanuk"}],"author_type":"wordpress","partnership_options":{"partnership_label":"","partner_logo":null,"partner_link":"","partnership_text":""},"override_related_posts":false,"related_posts":null,"right_cta_visibility":false,"sidebar_cta_content_override":false,"sidebar_cta_title":"","sidebar_cta_description":"","sidebar_cta_button":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local | SAIL Blogue<\/title>\n<meta name=\"description\" content=\"Pourquoi ne pas soutenir l\u2019achat local en offrant en cadeau un article de plein air d\u2019une marque d\u2019ici? D\u00e9couvrez nos suggestions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local\" \/>\n<meta property=\"og:description\" content=\"Soutenez l\u2019achat local en offrant un article de plein air d\u2019une marque d\u2019ici!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIL Blogue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SAILpleinairoutdoors\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T13:40:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T13:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SAIL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SAIL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/\"},\"author\":{\"name\":\"SAIL\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\"},\"headline\":\"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local\",\"datePublished\":\"2023-11-09T13:40:31+00:00\",\"dateModified\":\"2024-03-25T13:27:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2023\\\/11\\\/Marque-canadienne.jpg\",\"keywords\":[\"Id\u00e9es-cadeaux\",\"cadeaux\"],\"articleSection\":[\"Marques\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/\",\"name\":\"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local | SAIL Blogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2023\\\/11\\\/Marque-canadienne.jpg\",\"datePublished\":\"2023-11-09T13:40:31+00:00\",\"dateModified\":\"2024-03-25T13:27:38+00:00\",\"description\":\"Pourquoi ne pas soutenir l\u2019achat local en offrant en cadeau un article de plein air d\u2019une marque d\u2019ici? D\u00e9couvrez nos suggestions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2023\\\/11\\\/Marque-canadienne.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2023\\\/11\\\/Marque-canadienne.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Marque canadienne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/10-marques-achat-local-a-offrir-en-cadeau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marques\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/marques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"name\":\"SAIL Blogue\",\"description\":\"Blogue SAIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\",\"name\":\"SAIL\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"width\":1200,\"height\":630,\"caption\":\"SAIL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAILpleinairoutdoors\",\"https:\\\/\\\/www.instagram.com\\\/sailpleinairoutdoors\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\\\/blog\",\"https:\\\/\\\/www.youtube.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.tiktok.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.pinterest.com\\\/sailpleinairoutdoors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\",\"name\":\"SAIL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"caption\":\"SAIL\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local | SAIL Blogue","description":"Pourquoi ne pas soutenir l\u2019achat local en offrant en cadeau un article de plein air d\u2019une marque d\u2019ici? D\u00e9couvrez nos suggestions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/","og_locale":"fr_CA","og_type":"article","og_title":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local","og_description":"Soutenez l\u2019achat local en offrant un article de plein air d\u2019une marque d\u2019ici!","og_url":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/","og_site_name":"SAIL Blogue","article_publisher":"https:\/\/www.facebook.com\/SAILpleinairoutdoors","article_published_time":"2023-11-09T13:40:31+00:00","article_modified_time":"2024-03-25T13:27:38+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg","type":"image\/jpeg"}],"author":"SAIL","twitter_card":"summary_large_image","twitter_title":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local","twitter_misc":{"\u00c9crit par":"SAIL","Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#article","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/"},"author":{"name":"SAIL","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf"},"headline":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local","datePublished":"2023-11-09T13:40:31+00:00","dateModified":"2024-03-25T13:27:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/"},"wordCount":11,"publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg","keywords":["Id\u00e9es-cadeaux","cadeaux"],"articleSection":["Marques"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/","url":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/","name":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local | SAIL Blogue","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#primaryimage"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg","datePublished":"2023-11-09T13:40:31+00:00","dateModified":"2024-03-25T13:27:38+00:00","description":"Pourquoi ne pas soutenir l\u2019achat local en offrant en cadeau un article de plein air d\u2019une marque d\u2019ici? D\u00e9couvrez nos suggestions.","breadcrumb":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#primaryimage","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2023\/11\/Marque-canadienne.jpg","width":1080,"height":720,"caption":"Marque canadienne"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sail.ca\/blog\/fr\/10-marques-achat-local-a-offrir-en-cadeau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sail.ca\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Marques","item":"https:\/\/www.sail.ca\/blog\/fr\/marques\/"},{"@type":"ListItem","position":3,"name":"10 marques d\u2019ici \u00e0 offrir en cadeau pour soutenir l\u2019achat local"}]},{"@type":"WebSite","@id":"https:\/\/www.sail.ca\/blog\/fr\/#website","url":"https:\/\/www.sail.ca\/blog\/fr\/","name":"SAIL Blogue","description":"Blogue SAIL","publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sail.ca\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization","name":"SAIL","url":"https:\/\/www.sail.ca\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","width":1200,"height":630,"caption":"SAIL"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAILpleinairoutdoors","https:\/\/www.instagram.com\/sailpleinairoutdoors\/","https:\/\/www.linkedin.com\/company\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\/blog","https:\/\/www.youtube.com\/sailpleinairoutdoors","https:\/\/www.tiktok.com\/sailpleinairoutdoors","https:\/\/www.pinterest.com\/sailpleinairoutdoors\/"]},{"@type":"Person","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf","name":"SAIL","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","caption":"SAIL"}}]}},"_links":{"self":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/comments?post=12125"}],"version-history":[{"count":15,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12125\/revisions"}],"predecessor-version":[{"id":20255,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12125\/revisions\/20255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media\/19265"}],"wp:attachment":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media?parent=12125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/categories?post=12125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/tags?post=12125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}