{"id":12223,"date":"2021-11-05T15:12:16","date_gmt":"2021-11-05T20:12:16","guid":{"rendered":"https:\/\/www.sail.ca\/blog\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/"},"modified":"2022-09-15T14:47:31","modified_gmt":"2022-09-15T19:47:31","slug":"manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences","status":"publish","type":"post","link":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/","title":{"rendered":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":7746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[253,141,138],"tags":[1379],"class_list":["post-12223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-winter-jackets","category-manteaux-coquilles","category-vetements","tag-hiver"],"acf":{"post_flexible_content":[{"acf_fc_layout":"text_content","content_anchor":false,"anchor_link_text":"","text_content":"<span><strong>Pour profiter pleinement de vos sorties en plein air durant la saison hivernale, le syst\u00e8me multicouche est votre meilleur ami pour braver le froid. Or, chaque activit\u00e9 n\u00e9cessite d\u2019adapter votre tenue et c\u2019est pourquoi il peut devenir parfois difficile de choisir les v\u00eatements appropri\u00e9s lors d\u2019une activit\u00e9 en plein air. Voyez les diff\u00e9rences entre un manteau \u00e0 coquille souple ou rigide et comment faire le bon choix selon les activit\u00e9s auxquelles vous vous adonnez.<\/strong><\/span>\r\n\r\n<span>\u00c0 travers cet article, d\u00e9couvrez\u00a0:<\/span>\r\n<ol>\r\n \t<li><strong><span>Le manteau \u00e0 coquille souple ou rigide, c\u2019est quoi?<\/span><\/strong><\/li>\r\n \t<li><strong><span>Manteau \u00e0 coquille souple (\u00ab soft shell \u00bb)<\/span><\/strong>\r\n<ul>\r\n \t<li><span>Utilisation<\/span><\/li>\r\n \t<li><span>Imperm\u00e9abilit\u00e9<\/span><\/li>\r\n \t<li><span>Conditions m\u00e9t\u00e9orologiques<\/span><\/li>\r\n \t<li><span>Protection contre le froid<\/span><\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong><span>Manteau \u00e0 coquille rigide (\u00ab hard shell \u00bb)<\/span><\/strong>\r\n<ul>\r\n \t<li><span>Utilisation<\/span><\/li>\r\n \t<li><span>Imperm\u00e9abilit\u00e9<\/span><\/li>\r\n \t<li><span>Conditions m\u00e9t\u00e9orologiques<\/span><\/li>\r\n \t<li><span>Protection contre le froid<\/span><\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong><span>Entretien des coquilles souples et rigides<\/span><\/strong><\/li>\r\n<\/ol>\r\n\r\n<p style=\"text-align: center;\"><span>[stag_button url=\"https:\/\/www.sail.ca\/fr\/femme\/manteaux\/manteaux-coquilles\" style=\"orange\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Magasinez - Coquilles pour femme[\/stag_button][stag_button url=\"https:\/\/www.sail.ca\/fr\/homme\/manteaux\/manteaux-coquilles\" style=\"orange\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Magasinez - Coquilles pour homme[\/stag_button][stag_button url=\"https:\/\/www.sail.ca\/fr\/chaussures\/accessoires\/nettoyage-et-entretien\" style=\"orange\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Magasinez - Entretien et nettoyage[\/stag_button]<\/span><\/p>\r\n\r\n<h2>Le manteau \u00e0 coquille souple ou rigide, c\u2019est quoi?<\/h2>\r\n<span>Tout d\u2019abord, les manteaux \u00e0 coquille souple, commun\u00e9ment appel\u00e9s \u00ab soft shell \u00bb, sont fabriqu\u00e9s de divers mat\u00e9riaux tels que le polyester et le nylon pour former une combinaison \u00e0 la fois durable et confortable. Ce type de manteau est id\u00e9al pour certains types d\u2019activit\u00e9s et conditions m\u00e9t\u00e9orologiques. Pour sa part, le manteau \u00e0 coquille rigide, aussi appel\u00e9 \u00ab hard shell \u00bb, est fait de mat\u00e9riaux imperm\u00e9ables tr\u00e8s performants et il est con\u00e7u pour des temp\u00e9ratures extr\u00eames.<\/span>\r\n\r\n\r\n\r\n\r\n<h3>Principales diff\u00e9rences des deux types de coquilles<\/h3>\r\n<img class=\"aligncenter wp-image-7723 size-large\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/fr-comparaison-harshell-softshell-1024x597.jpg\" alt=\"coquille souple et coquille rigide diff\u00e9rences\" width=\"770\" height=\"449\" \/>\r\n<h3>Manteau \u00e0 coquille souple<\/h3>\r\n<ul>\r\n \t<li><span>Activit\u00e9s : de haute intensit\u00e9<\/span><\/li>\r\n \t<li><span>Respirabilit\u00e9 : haute<\/span><\/li>\r\n \t<li><span>Imperm\u00e9abilit\u00e9 : moyenne<\/span><\/li>\r\n \t<li><span>Protection contre le froid : bonne, lorsque superpos\u00e9 avec d\u2019autres couches de v\u00eatements<\/span><\/li>\r\n \t<li><span>Conditions m\u00e9t\u00e9orologiques : temp\u00e9rature fra\u00eeche et faible pluie<\/span><\/li>\r\n<\/ul>\r\n\r\n<h3>Manteau \u00e0 coquille rigide<\/h3>\r\n<ul>\r\n \t<li><span>Activit\u00e9s : faible intensit\u00e9<\/span><\/li>\r\n \t<li><span>Respirabilit\u00e9 : moyenne<\/span><\/li>\r\n \t<li><span>Imperm\u00e9abilit\u00e9 : excellente<\/span><\/li>\r\n \t<li><span>Protection contre le froid : bonne, lorsque superpos\u00e9 avec une couche isolante<\/span><\/li>\r\n \t<li><span>Conditions m\u00e9t\u00e9orologiques : temp\u00eates, forte pluie, neige, vent, etc.<\/span><\/li>\r\n<\/ul>\r\n\r\n<h2>Manteau \u00e0 coquille souple (\u00ab soft shell\u00bb)<\/h2>\r\n<h3>Utilisation<\/h3>\r\n<span>Le manteau \u00e0 coquille souple est \u00e0 privil\u00e9gier lors des activit\u00e9s ext\u00e9rieures qui n\u00e9cessitent un certain effort physique comme le <a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-d-hiver\/ski-de-fond\" target=\"_blank\" rel=\"noopener\">ski de fond,<\/a> la <a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-d-hiver\/raquettes-a-neige\" target=\"_blank\" rel=\"noopener\">raquette<\/a> ou encore le<a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/sports-d-hiver\/ski-de-haute-route\" target=\"_blank\" rel=\"noopener\"> ski de haute route<\/a>. En effet, la principale caract\u00e9ristique de la coquille souple est sa respirabilit\u00e9. Ce type de manteau s\u2019av\u00e8re particuli\u00e8rement int\u00e9ressant pour les activit\u00e9s o\u00f9 vous risquez de transpirer. Souvent fabriqu\u00e9e de nylon extensible, la coquille souple offre une excellente amplitude de mouvement, ce qui permet de bouger confortablement lors de vos aventures en plein air.<\/span>\r\n\r\n\r\n<h3>Imperm\u00e9abilit\u00e9<\/h3>\r\n<span>La coquille souple poss\u00e8de une tr\u00e8s bonne capacit\u00e9 coupe-vent, mais ne sera pas \u00e9tanche \u00e0 l\u2019eau. Toutefois, elle offre une r\u00e9sistance \u00e0 l\u2019eau et aux intemp\u00e9ries. En effet, la majorit\u00e9 des coquilles souples sont munies d\u2019un traitement d\u00e9perlant, ce qui permet \u00e0 l\u2019eau de perler sur la fibre ext\u00e9rieure de nylon. De plus, il est possible de renouveler ce traitement d\u00e9perlant chaque saison pour optimiser la r\u00e9sistance et la durabilit\u00e9 du manteau.<\/span>\r\n\r\n\r\n<h3>Conditions m\u00e9t\u00e9orologiques<\/h3>\r\n<span>Le manteau \u00e0 coquille souple, ou \u00absoft shell\u00bb, procure une excellente r\u00e9sistance au vent. Pour permettre un \u00e9change d\u2019humidit\u00e9 optimal, la coquille souple ne bloquera pas la totalit\u00e9 du vent. Pour une activit\u00e9 avec une temp\u00e9rature froide et venteuse, il est avantageux de choisir une coquille souple plut\u00f4t qu\u2019une coquille rigide, pour la simple raison que celle-ci permettra une meilleure respirabilit\u00e9 et amplitude de mouvement.<\/span>\r\n\r\n\r\n<h3>Protection contre le froid<\/h3>\r\n<span>Les manteaux \u00e0 coquille souple offrent une certaine protection contre le froid, gr\u00e2ce \u00e0 leur int\u00e9rieur qui sont souvent con\u00e7us en micropolaire. Ainsi, le degr\u00e9 d\u2019isolation est optimis\u00e9 et permet \u00e0 ce manteau d'\u00eatre optimal pour des temp\u00e9ratures fra\u00eeches. Les coquilles souples sont plus efficaces lorsqu\u2019elles sont superpos\u00e9es avec d'autres couches de v\u00eatements, comme le stipule le <a href=\"https:\/\/www.sail.ca\/blog\/fr\/multicouche-superposer-pour-rester-chaud-2\/\" target=\"_blank\" rel=\"noopener\">syst\u00e8me multicouche<\/a>. Celles-ci sont g\u00e9n\u00e9ralement con\u00e7ues pour \u00eatre des couches interm\u00e9diaires. Cette technique augmentera la capacit\u00e9 de protection contre le froid de votre coquille souple.<\/span>\r\n<p style=\"text-align: center;\">[stag_button url=\"https:\/\/www.sail.ca\/fr\/femme\/manteaux\/manteaux-coquilles\" style=\"orange\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Magasinez - Coquilles pour femme[\/stag_button]\r\n[stag_button url=\"https:\/\/www.sail.ca\/fr\/homme\/manteaux\/manteaux-coquilles\" style=\"orange\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Magasinez - Coquilles pour homme[\/stag_button]<\/p>\r\n\r\n\r\n\r\n<h2>Manteau \u00e0 coquille rigide ( \u00abhard shell\u00bb)<\/h2>\r\n<h3>Utilisation<\/h3>\r\n<span>De son c\u00f4t\u00e9, la coquille rigide est reconnue pour offrir une moins bonne respirabilit\u00e9 et amplitude de mouvement que la coquille souple. C\u2019est pourquoi elle est avantageuse lors de sorties en plein air qui n\u00e9cessitent moins d\u2019efforts physiques ou lorsque la m\u00e9t\u00e9o n\u2019est pas de votre c\u00f4t\u00e9. Par exemple, une coquille rigide est optimale pour la<a href=\"https:\/\/www.sail.ca\/fr\/plein-air\/randonnee-pedestre\" target=\"_blank\" rel=\"noopener\"> randonn\u00e9e p\u00e9destr<\/a>e et elle est habituellement utilis\u00e9e comme couche ext\u00e9rieure selon le syst\u00e8me multicouche.<\/span>\r\n\r\n\r\n<h3>Imperm\u00e9abilit\u00e9<\/h3>\r\n<span>La coquille rigide offre une excellente protection contre l\u2019eau et les intemp\u00e9ries extr\u00eames, comme de la pluie abondante ou une temp\u00eate de neige. La coquille rigide offre une meilleure imperm\u00e9abilit\u00e9 que la coquille souple en raison des tissus qui la composent. Souvent fait de Gore-Tex, ce type de manteau permet de pratiquer vos activit\u00e9s de plein air favorites, et ce, m\u00eame sous la pluie!<\/span>\r\n\r\n\r\n<h3>Conditions m\u00e9t\u00e9orologiques<\/h3>\r\n<span>Les coquilles rigides procurent une protection int\u00e9grale contre toutes les intemp\u00e9ries. Elles sont con\u00e7ues pour des conditions m\u00e9t\u00e9orologiques particuli\u00e8res : pluie, neige, rafales, ou encore taux d\u2019humidit\u00e9 \u00e9lev\u00e9, rien ne r\u00e9siste aux coquilles rigides.<\/span>\r\n\r\n\r\n<h3>Protection contre le froid<\/h3>\r\n<span>Tout comme la coquille souple, la coquille rigide offre une certaine protection contre le froid. G\u00e9n\u00e9ralement con\u00e7ue pour \u00eatre port\u00e9e comme couche ext\u00e9rieure, la couche isolante qui se trouve en dessous de la coquille rigide permet au corps de garder sa chaleur. Bref, pour une protection optimale contre le froid avec une coquille souple ou rigide, assurez-vous de bien suivre le syst\u00e8me multicouche.<\/span>\r\n\r\n\r\n<h2>Entretien des coquilles souples et rigides<\/h2>\r\n<span>L\u2019entretien des coquilles souples et rigides joue un grand r\u00f4le dans leur efficacit\u00e9 au fil du temps. Chaque mat\u00e9riel poss\u00e8de ses propres caract\u00e9ristiques, alors vous pouvez vous r\u00e9f\u00e9rer aux indications qui se trouvent sur les \u00e9tiquettes de vos coquilles.<\/span>\r\n\r\n<span>G\u00e9n\u00e9ralement, il est possible de les laver \u00e0 la machine \u00e0 un cycle d\u00e9licat. Avant de les laver, il est recommand\u00e9 de fermer toutes les fermetures \u00e0 glissi\u00e8re. Assurez-vous \u00e9galement que la temp\u00e9rature soit tr\u00e8s basse, et n\u2019ajoutez pas d\u2019assouplisseur. Pour le s\u00e9chage, il est pr\u00e9f\u00e9rable de les faire s\u00e9cher \u00e0 l\u2019air et de ne pas les mettre dans la s\u00e9cheuse. <\/span>\r\n\r\n<span>Suite au lavage, vous pouvez appliquer des <a href=\"https:\/\/www.sail.ca\/fr\/chaussures\/accessoires\/nettoyage-et-entretien\" target=\"_blank\" rel=\"noopener\">traitements d\u00e9perlants<\/a> pour conserver l\u2019imperm\u00e9abilit\u00e9 de votre coquille et l\u2019utiliser encore longtemps.<\/span>\r\n\r\n\r\n\r\n"}],"author_type":"wordpress","partnership_options":{"partnership_label":"","partner_logo":null,"partner_link":"","partnership_text":""},"override_related_posts":false,"related_posts":null,"right_cta_visibility":false,"sidebar_cta_content_override":false,"sidebar_cta_title":"","sidebar_cta_description":"","sidebar_cta_button":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences? | SAIL Blogue<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIL Blogue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SAILpleinairoutdoors\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T20:12:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T19:47:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SAIL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SAIL\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/\"},\"author\":{\"name\":\"SAIL\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\"},\"headline\":\"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?\",\"datePublished\":\"2021-11-05T20:12:16+00:00\",\"dateModified\":\"2022-09-15T19:47:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/11\\\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg\",\"keywords\":[\"Hiver\"],\"articleSection\":[\"Winter Jackets\",\"Manteaux coquilles\",\"V\u00eatements\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/\",\"name\":\"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences? | SAIL Blogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/11\\\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg\",\"datePublished\":\"2021-11-05T20:12:16+00:00\",\"dateModified\":\"2022-09-15T19:47:31+00:00\",\"description\":\"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/11\\\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/11\\\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Homme en for\u00eat qui porte une coquille rigide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eatements\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/clothing\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manteaux d'hiver\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/clothing\\\/winter-jackets\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"name\":\"SAIL Blogue\",\"description\":\"Blogue SAIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\",\"name\":\"SAIL\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"width\":1200,\"height\":630,\"caption\":\"SAIL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAILpleinairoutdoors\",\"https:\\\/\\\/www.instagram.com\\\/sailpleinairoutdoors\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\\\/blog\",\"https:\\\/\\\/www.youtube.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.tiktok.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.pinterest.com\\\/sailpleinairoutdoors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\",\"name\":\"SAIL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"caption\":\"SAIL\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences? | SAIL Blogue","description":"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/","og_locale":"fr_CA","og_type":"article","og_title":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?","og_description":"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.","og_url":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/","og_site_name":"SAIL Blogue","article_publisher":"https:\/\/www.facebook.com\/SAILpleinairoutdoors","article_published_time":"2021-11-05T20:12:16+00:00","article_modified_time":"2022-09-15T19:47:31+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg","type":"image\/jpeg"}],"author":"SAIL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"SAIL"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#article","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/"},"author":{"name":"SAIL","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf"},"headline":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?","datePublished":"2021-11-05T20:12:16+00:00","dateModified":"2022-09-15T19:47:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg","keywords":["Hiver"],"articleSection":["Winter Jackets","Manteaux coquilles","V\u00eatements"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/","url":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/","name":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences? | SAIL Blogue","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#primaryimage"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg","datePublished":"2021-11-05T20:12:16+00:00","dateModified":"2022-09-15T19:47:31+00:00","description":"D\u00e9couvrez les principales diff\u00e9rences entre une coquille souple ou rigide et faites un choix \u00e9clair\u00e9 adapt\u00e9 \u00e0 vos besoins. Lisez l\u2019article.","breadcrumb":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#primaryimage","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/11\/couquilles-souples-ou-coquilles-rigides-les-differences-1200x628px.jpg","width":1200,"height":628,"caption":"Homme en for\u00eat qui porte une coquille rigide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sail.ca\/blog\/fr\/manteau-a-coquille-souple-ou-rigide-quelles-sont-les-differences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sail.ca\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"V\u00eatements","item":"https:\/\/www.sail.ca\/blog\/clothing\/"},{"@type":"ListItem","position":3,"name":"Manteaux d'hiver","item":"https:\/\/www.sail.ca\/blog\/clothing\/winter-jackets\/"},{"@type":"ListItem","position":4,"name":"Manteau \u00e0 coquille souple ou rigide : quelles sont les diff\u00e9rences?"}]},{"@type":"WebSite","@id":"https:\/\/www.sail.ca\/blog\/fr\/#website","url":"https:\/\/www.sail.ca\/blog\/fr\/","name":"SAIL Blogue","description":"Blogue SAIL","publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sail.ca\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization","name":"SAIL","url":"https:\/\/www.sail.ca\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","width":1200,"height":630,"caption":"SAIL"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAILpleinairoutdoors","https:\/\/www.instagram.com\/sailpleinairoutdoors\/","https:\/\/www.linkedin.com\/company\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\/blog","https:\/\/www.youtube.com\/sailpleinairoutdoors","https:\/\/www.tiktok.com\/sailpleinairoutdoors","https:\/\/www.pinterest.com\/sailpleinairoutdoors\/"]},{"@type":"Person","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf","name":"SAIL","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","caption":"SAIL"}}]}},"_links":{"self":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/comments?post=12223"}],"version-history":[{"count":1,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12223\/revisions"}],"predecessor-version":[{"id":12248,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12223\/revisions\/12248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media\/7746"}],"wp:attachment":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media?parent=12223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/categories?post=12223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/tags?post=12223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}