{"id":12271,"date":"2024-03-24T14:03:50","date_gmt":"2024-03-24T19:03:50","guid":{"rendered":"https:\/\/www.sail.ca\/blog\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/"},"modified":"2024-03-25T13:39:40","modified_gmt":"2024-03-25T18:39:40","slug":"chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse","status":"publish","type":"post","link":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/","title":{"rendered":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":20268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[125,131],"tags":[1414,1626],"class_list":["post-12271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chasse","category-chasse-oiseaux-migrateurs","tag-fedecp","tag-printemps"],"acf":{"post_flexible_content":[{"acf_fc_layout":"text_content","content_anchor":false,"anchor_link_text":"","text_content":"<strong>La chasse aux oiseaux migrateurs et \u00e0 la sauvagine est bien contr\u00f4l\u00e9e afin de permettre la conservation des diff\u00e9rentes esp\u00e8ces et de leurs habitats. Lisez ces conseils pour en conna\u00eetre davantage sur la r\u00e9glementation et sur le mat\u00e9riel dont vous aurez besoin pour chasser les oiseaux migrateurs.<\/strong>\r\n\r\n<a href=\"https:\/\/fedecp.com\/\" target=\"_blank\" rel=\"noopener\"><img class=\"wp-image-7369 alignleft\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/fedecp-300x173.png\" alt=\"Logo de la F\u00c9D\u00c9CP\" width=\"162\" height=\"93\" \/><\/a>\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n\r\n<em><strong>Cet article a \u00e9t\u00e9 produit en collaboration avec la <a href=\"https:\/\/fedecp.com\/\" target=\"_blank\" rel=\"noopener\">F\u00e9d\u00e9CP<\/a>.<\/strong><\/em>"},{"acf_fc_layout":"content_anchors_list","anchors_section_title":"Dans cet article, vous trouverez des informations qui vous seront utiles si vous faites vos premiers pas dans la chasse aux oiseaux migrateurs et \u00e0 la sauvagine :"},{"acf_fc_layout":"text_content","content_anchor":false,"anchor_link_text":"","text_content":"<p style=\"text-align: center;\">[stag_button url=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\" style=\"black\" size=\"medium\" type=\"normal\" target=\"_blank\" icon=\"\" icon_order=\"before\"]Chasse \u00e0 la sauvagine[\/stag_button]<\/p>"},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Les informations de base \u00e0 conna\u00eetre","text_content":"<h2>Chasse aux oiseaux migrateurs : Les informations de base \u00e0 conna\u00eetre<\/h2>\r\n<h3>Quelle est la diff\u00e9rence entre la chasse \u00e0 la sauvagine et la chasse aux oiseaux migrateurs?<\/h3>\r\nEn fait, il s'agit du m\u00eame type de chasse, avec les m\u00eames techniques, le m\u00eame \u00e9quipement et les m\u00eames permis. Le terme \u00ab sauvagine \u00bb d\u00e9signe les esp\u00e8ces d'oiseaux migrateurs qui vivent sur et pr\u00e8s de l'eau, comme les canards, les oies et les bernaches. Les oiseaux migrateurs regroupent entre autres les b\u00e9cassines, les b\u00e9casses, les tourterelles tristes et les diff\u00e9rentes esp\u00e8ces de sauvagine.\r\n<h3>Quels permis faut-il poss\u00e9der pour la chasse aux oiseaux migrateurs?<\/h3>\r\nPour chasser les oiseaux migrateurs, vous devez d\u00e9tenir un permis provincial de chasse au petit gibier ainsi qu'un <a href=\"https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/chasse-oiseaux-migrateurs-gibier\/permis.html\" target=\"_blank\" rel=\"noopener\">permis f\u00e9d\u00e9ral de chasse aux oiseaux migrateurs<\/a> sur lequel figure le timbre sur la conservation des habitats fauniques du Canada. Vous devez porter les deux permis sur vous lorsque vous chassez.\r\n\r\nLe permis f\u00e9d\u00e9ral de chasse aux oiseaux migrateurs consid\u00e9r\u00e9s comme gibier peut \u00eatre <a href=\"https:\/\/www.permis-permits.ec.gc.ca\/fr\/Achatdunpermisdechasse\" target=\"_blank\" rel=\"noopener\">achet\u00e9 en ligne ou dans certaines succursales de Postes Canada<\/a>.\r\n\r\nVous pouvez trouver plus d\u2019informations sur le permis provincial de chasse au petit gibier en visitant le site Web du <a href=\"https:\/\/www.quebec.ca\/tourisme-et-loisirs\/activites-sportives-et-de-plein-air\/chasse-sportive\/permis-certificat\/acheter-permis\" target=\"_blank\" rel=\"noopener\">gouvernement du Qu\u00e9bec<\/a> ou celui du <a href=\"https:\/\/www.ontario.ca\/fr\/document\/resume-des-reglements-de-la-chasse\/renseignements-sur-les-permis-de-chasse\" target=\"_blank\" rel=\"noopener\">gouvernement de l\u2019Ontario<\/a>.\r\n<h3>Quels oiseaux migrateurs peut-on chasser au Qu\u00e9bec et quelle est la p\u00e9riode de chasse?<\/h3>\r\nLes esp\u00e8ces principales :\r\n<ul>\r\n \t<li>Canards<\/li>\r\n \t<li>Oies et oies des neiges<\/li>\r\n \t<li>Bernaches, bernaches de Hutchins et bernaches du Canada<\/li>\r\n \t<li>B\u00e9casses<\/li>\r\n \t<li>B\u00e9cassines<\/li>\r\n \t<li>Foulques<\/li>\r\n \t<li>Gallinules<\/li>\r\n \t<li>Tourterelles tristes<\/li>\r\n<\/ul>\r\nLes dates de chasse :\r\n\r\nLes dates de la saison de<a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\" target=\"_blank\" rel=\"noopener\"> chasse \u00e0 la sauvagine<\/a> et aux oiseaux migrateurs varient selon le district et selon l'esp\u00e8ce. De fa\u00e7on g\u00e9n\u00e9rale, les oiseaux migrateurs sont chass\u00e9s \u00e0 l\u2019automne entre septembre et d\u00e9cembre au Qu\u00e9bec. Pour l\u2019oie des neiges, consid\u00e9r\u00e9e comme une esp\u00e8ce surabondante, une p\u00e9riode de r\u00e9colte de conservation est aussi pr\u00e9vue au printemps. Les dates varient aussi selon le district, mais la chasse s\u2019effectue g\u00e9n\u00e9ralement entre mars et juin.\r\n\r\nPour plus d\u2019informations, visitez la <a href=\"https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/chasse-oiseaux-migrateurs-gibier\/reglementation-resumes-provinciaux-territoriaux\/quebec.html\" target=\"_blank\" rel=\"noopener\">section sur la chasse aux oiseaux migrateurs au Qu\u00e9bec<\/a> sur le site Web du gouvernement du Canada.\r\n<h3>Quels oiseaux migrateurs peut-on chasser en Ontario et quelle est la p\u00e9riode de chasse?<\/h3>\r\nLes esp\u00e8ces principales :\r\n<ul>\r\n \t<li>Canards<\/li>\r\n \t<li>R\u00e2les<\/li>\r\n \t<li>Oies et oies des neiges<\/li>\r\n \t<li>Bernaches, bernaches de Hutchins et bernaches du Canada<\/li>\r\n \t<li>B\u00e9casses<\/li>\r\n \t<li>B\u00e9cassines<\/li>\r\n \t<li>Foulques<\/li>\r\n \t<li>Gallinules<\/li>\r\n \t<li>Tourterelles tristes<\/li>\r\n<\/ul>\r\nLes dates de chasse :\r\n\r\nLes dates varient selon le district et selon l'esp\u00e8ce, mais de fa\u00e7on g\u00e9n\u00e9rale, la sauvagine et les oiseaux migrateurs sont chass\u00e9s entre les mois de septembre et d\u00e9cembre en Ontario. Il y a \u00e9galement une p\u00e9riode sp\u00e9ciale de r\u00e9colte de conservation au printemps pour l'<a href=\"https:\/\/www.youtube.com\/watch?v=s5x8ulkWyGg\" target=\"_blank\" rel=\"noopener\">oie des neiges<\/a> et l'oie de Ross, qui sont consid\u00e9r\u00e9es comme des esp\u00e8ces surabondantes. La chasse de conservation a lieu entre le 1er mars et le 31 mai.\r\n\r\nPour plus d\u2019informations, visitez la <a href=\"https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/chasse-oiseaux-migrateurs-gibier\/reglementation-resumes-provinciaux-territoriaux\/ontario.html\" target=\"_blank\" rel=\"noopener\">section sur la chasse aux oiseaux migrateurs en Ontario<\/a> sur le site Web du gouvernement du Canada.\r\n<h3>Quelles sont les limites de prise?<\/h3>\r\nLes nombres maximums de prises et d'oiseaux \u00e0 poss\u00e9der diff\u00e8rent entre le Qu\u00e9bec et l'Ontario et varient selon l'esp\u00e8ce. Vous pouvez trouver toutes les informations concernant votre zone de chasse (district) en consultant la <a href=\"https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/chasse-oiseaux-migrateurs-gibier\/reglementation-resumes-provinciaux-territoriaux.html\" target=\"_blank\" rel=\"noopener\">R\u00e9glementation sur la chasse aux oiseaux migrateurs<\/a> sur le site Web du gouvernement du Canada.\r\n\r\nSi vous chassez au Qu\u00e9bec, il existe aussi une application mobile appel\u00e9e Zone de chasse qui fournit des informations d\u00e9taill\u00e9es sur les districts, les dates, les esp\u00e8ces et les limites de prise."},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Les accessoires essentiels \u00e0 apporter","text_content":"<h2>L'\u00e9quipement et les accessoires essentiels \u00e0 apporter<\/h2>\r\n<h3><img class=\"size-full wp-image-20266 aligncenter\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/2.png\" alt=\"\u00c9quipement chasse \u00e0 la sauvagine\" width=\"1080\" height=\"720\" \/><\/h3>\r\n<h3>Quels sont les essentiels pour la chasse \u00e0 la sauvagine et aux oiseaux migrateurs?<\/h3>\r\nUn ou plusieurs <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/appeaux\" target=\"_blank\" rel=\"noopener\">appeaux<\/a> vous permettant de reproduire les sons de l\u2019esp\u00e8ce que vous souhaitez r\u00e9colter. Les appeaux sont des outils pr\u00e9cieux pour la chasse aux oiseaux migrateurs et \u00e0 la <a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\/appelants-et-appeaux\" target=\"_blank\" rel=\"noopener\">sauvagine<\/a>; ils peuvent \u00eatre tr\u00e8s efficaces pour attirer les oiseaux et les inciter \u00e0 s'approcher. Ne l\u00e9sinez pas sur la qualit\u00e9 et veillez \u00e0 bien vous pratiquer avant le jour J, car des appels mal ex\u00e9cut\u00e9s risquent de rendre les oiseaux m\u00e9fiants ou m\u00eame de les faire fuir.\r\n\r\nUne bonne quantit\u00e9 <a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\/appelants-et-appeaux\" target=\"_blank\" rel=\"noopener\">d'appelants<\/a> ressemblant de pr\u00e8s \u00e0 l'esp\u00e8ce vis\u00e9e afin d'attirer les oiseaux pr\u00e8s de vous. Il en existe de toutes sortes : m\u00e2les ou femelles, taille r\u00e9elle ou plus grande pour une meilleure visibilit\u00e9, couleurs de plumage et positions vari\u00e9es, et bien s\u00fbr, diff\u00e9rentes esp\u00e8ces de <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/appelants\/canard\" target=\"_blank\" rel=\"noopener\">canards<\/a>, <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/appelants\/oie\" target=\"_blank\" rel=\"noopener\">oies<\/a>, bernaches, etc. Pr\u00e9voyez id\u00e9alement au moins 12 appelants de bonne qualit\u00e9, et installez-les avec soin pour que la sc\u00e8ne ait l\u2019air aussi r\u00e9aliste que possible.\r\n\r\nUne cache vous permettant de vous fondre dans votre environnement et d'attendre votre proie sans qu'elle vous voie. Vous pouvez utiliser diff\u00e9rents types de caches pour la chasse aux oiseaux migrateurs, selon l'esp\u00e8ce vis\u00e9e et l'endroit o\u00f9 vous chassez (nous y reviendrons un peu plus loin!).\r\n\r\nUn <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/vetements-de-chasse\/manteaux-et-impermeables\" target=\"_blank\" rel=\"noopener\">manteau de chasse<\/a> chaud et imperm\u00e9able qui vous rend invisible aux yeux de votre proie et vous prot\u00e8ge des \u00e9l\u00e9ments. Le <a href=\"https:\/\/www.sail.ca\/blog\/leaf-camouflage-vs-pixelated-camouflage\/\" target=\"_blank\" rel=\"noopener\">camouflage<\/a> n'est pas \u00e0 n\u00e9gliger, d\u2019autant plus que les sauvagines ont une excellente vision. Optez pour un manteau imperm\u00e9able et assez isol\u00e9 pour affronter les temp\u00e9ratures froides (et souvent changeantes) des saisons de transition, et n'oubliez pas qu'il y aura sans doute plusieurs moments d'immobilit\u00e9 au cours de votre partie de chasse aux oiseaux migrateurs.\r\n\r\nDes <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/vetements-de-chasse\/pantalons\" target=\"_blank\" rel=\"noopener\">pantalons<\/a> de chasse ou des <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/bottes-de-chasse\/bottes-pantalon\" target=\"_blank\" rel=\"noopener\">bottes-pantalon<\/a> vous permettant de sillonner les champs, de marcher dans l'eau et de vous d\u00e9placer sans difficult\u00e9, peu importe les conditions. Privil\u00e9giez les couleurs et les motifs qui se camouflent bien dans votre environnement de chasse, et portez des couches respirantes en dessous pour rester au chaud et au sec tout au long de la journ\u00e9e.\r\nLes bonnes armes \u00e0 feu pour la chasse aux oiseaux migrateurs et \u00e0 la sauvagine.\r\n<h3>Les bonnes armes \u00e0 feu pour la chasse aux oiseaux migrateurs et \u00e0 la sauvagine<\/h3>\r\nLa majorit\u00e9 des chasseurs utilisent un <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/armes-a-feu\/fusils\" target=\"_blank\" rel=\"noopener\">fusil de chasse<\/a> pour cibler les oiseaux migrateurs et la sauvagine. Veillez \u00e0 choisir un fusil confortable, que vous pourrez lever et \u00e9pauler avec aisance au moment de viser votre cible et d'effectuer un tir.\r\n\r\nLes fusils de chasse de calibre 12 sont les <a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\/armes-a-feu\" target=\"_blank\" rel=\"noopener\">armes \u00e0 feu<\/a> les plus populaires pour la chasse \u00e0 la sauvagine, car ils sont puissants tout en ayant un recul mod\u00e9r\u00e9. Ce calibre permet \u00e9galement d'utiliser une grande vari\u00e9t\u00e9 de munitions. Les personnes qui ont un petit gabarit ou qui cherchent une arme avec un recul minimal peuvent aussi opter pour un fusil de chasse de calibre 20. Comme ce calibre offre moins de puissance, il faudra toutefois pr\u00e9voir une distance plus courte entre le chasseur et sa cible.\r\n\r\nPour ce qui est des <a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/chasse-a-la-sauvagine\/munitions\" target=\"_blank\" rel=\"noopener\">munitions<\/a>, tournez-vous vers des cartouches \u00e0 grenaille d'acier d'une longueur de 3 \u00e0 3,5 pouces. L'utilisation de grenaille de plomb pour la chasse aux oiseaux migrateurs est interdite au Canada, mais d'autres options non toxiques comme le bismuth et le tungst\u00e8ne peuvent aussi \u00eatre utilis\u00e9es. La taille des cartouches d\u00e9pend de l'esp\u00e8ce cibl\u00e9e; vous pouvez par exemple utiliser les tailles 2 et 3 pour la chasse aux canards, les tailles 1, 2 ou BB pour la chasse \u00e0 l'oie des neiges, et les tailles 1, 2, BB ou BBB pour la chasse \u00e0 la bernache du Canada.\r\n<h3>Les chiens rapporteurs : un atout pr\u00e9cieux pour la chasse \u00e0 la sauvagine<\/h3>\r\nUn compagnon \u00e0 quatre pattes peut \u00eatre un merveilleux partenaire de chasse, et sa pr\u00e9sence peut r\u00e9ellement augmenter vos chances de r\u00e9ussite, quel que soit le type de gibier que vous visez. Pour la chasse \u00e0 la sauvagine, les chiens rapporteurs en particulier sont d'une aide pr\u00e9cieuse, car ils se jettent volontiers \u00e0 l'eau pour aller r\u00e9cup\u00e9rer la r\u00e9colte. Les <a href=\"https:\/\/www.sail.ca\/blog\/fr\/meilleures-races-de-chiens-de-chasse\/\" target=\"_blank\" rel=\"noopener\">chiens de chasse<\/a> de race labrador et golden retriever, notamment, sont des compagnons enthousiastes qui adorent l'eau et poss\u00e8dent d'excellentes aptitudes pour la chasse aux oiseaux migrateurs."},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"Les types de caches \u00e0 utiliser","text_content":"<h2>Les types de caches pour la chasse aux oiseaux migrateurs et \u00e0 la sauvagine<\/h2>\r\nTrois types de caches sont particuli\u00e8rement efficaces pour la chasse aux oiseaux migrateurs. Pour que votre installation soit adapt\u00e9e \u00e0 votre zone de chasse, utilisez la v\u00e9g\u00e9tation que vous trouverez dans les environs pour dissimuler votre cache \u00e0 la vision tr\u00e8s pointue des oies et autres sauvagines.\r\n<h3>Les caches en A<\/h3>\r\nLes <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/accessoires-de-chasse\/miradors-et-abris-de-chasse\" target=\"_blank\" rel=\"noopener\">caches<\/a> de type \u00ab A-Frame \u00bb, en forme de bunker, sont g\u00e9n\u00e9ralement install\u00e9es dans un foss\u00e9 ou en p\u00e9riph\u00e9rie d'un champ, puis recouvertes de boue, de brindilles et de v\u00e9g\u00e9tation ramass\u00e9es sur le terrain afin qu'elles se fondent parfaitement dans l'environnement de chasse. Gr\u00e2ce \u00e0 leur structure faite de p\u00f4les et de panneaux, elles ont l'avantage d'offrir un couvert complet et sont donc id\u00e9ales pour \u00e9chapper \u00e0 la vue des oiseaux qui survolent la zone. Avec une cache en A, les chasseurs peuvent en plus tirer debout, comme au tir au pigeon d'argile, ce qui favorise g\u00e9n\u00e9ralement un maximum de pr\u00e9cision.\r\n<h3>Les caches \u00ab bed \u00bb<\/h3>\r\nUtilis\u00e9es sp\u00e9cifiquement pour la <a href=\"https:\/\/www.sail.ca\/blog\/fr\/chasse-a-loie-blanche-nos-conseils-pour-vous-preparer-a-la-saison-2024\/\" target=\"_blank\" rel=\"noopener\">chasse \u00e0 l'oie blanche<\/a>, ces caches en forme de si\u00e8ge permettent aux chasseurs de se camoufler au niveau du sol parmi leurs <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/appelants\/oie\" target=\"_blank\" rel=\"noopener\">appelants<\/a>. Dans ce genre de cache \u00ab ouverte \u00bb, il est important de toujours se placer plus bas que les appelants afin de rester aussi peu visible que possible. Cela en vaut la peine, car les caches de type \u00ab bed \u00bb permettent de vivre des exp\u00e9riences de chasse extraordinaires et d'avoir une vue imprenable de l'approche des oiseaux.\r\n<h3>Les caches tombeau<\/h3>\r\nLes caches tombeau au profil bas, pr\u00e8s du sol, se pr\u00eatent bien \u00e0 la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, car elles se dissimulent facilement \u00e0 l\u2019aide d\u2019herbes et de brindilles dans les champs et les endroits o\u00f9 la v\u00e9g\u00e9tation est basse. Les caches de ce type doivent comporter des ouvertures afin que le chasseur ait une vue d'ensemble et puisse bien viser les oiseaux en approche avant de soulever le panneau sup\u00e9rieur et de se redresser pour tirer. Ce moment est critique, car les oiseaux per\u00e7oivent alors le danger presque instantan\u00e9ment - d'o\u00f9 l'importance d'une action rapide et r\u00e9fl\u00e9chie."},{"acf_fc_layout":"text_content","content_anchor":true,"anchor_link_text":"L\u2019entra\u00eenement au tir au pigeon d'argile","text_content":"<h2>Le tir \u00e0 la vol\u00e9e : un bon entra\u00eenement pour la chasse aux oiseaux migrateurs<\/h2>\r\n<img class=\"size-full wp-image-20267 aligncenter\" src=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/3.png\" alt=\"Le tir \u00e0 la vol\u00e9e\" width=\"1080\" height=\"720\" \/>\r\n\r\nLe <a href=\"https:\/\/www.sail.ca\/fr\/collections\/chasse\/pigeon-d-argile\" target=\"_blank\" rel=\"noopener\">tir au pigeon d'argile<\/a> est un excellent moyen de parfaire vos habilet\u00e9s pour la chasse aux oiseaux migrateurs, que vous souhaitiez vous pr\u00e9parer pour la saison \u00e0 venir ou travailler votre technique pendant les mois sans chasse. Les sauvagines et les oiseaux migrateurs volent vite (surtout les canards); vous devez donc \u00eatre en mesure de vous placer, de viser et de tirer avec rapidit\u00e9 et efficacit\u00e9 pour r\u00e9ussir vos parties de chasse. Ce sont l\u00e0 toutes des habilet\u00e9s que vous pouvez perfectionner gr\u00e2ce au tir \u00e0 la vol\u00e9e (ou \u00ab trap \u00bb).\r\n\r\nCette forme de <a href=\"https:\/\/www.sail.ca\/blog\/fr\/le-tir-au-pigeon-dargile-la-pratique-avant-la-chasse\/\" target=\"_blank\" rel=\"noopener\">tir au pigeon d'argile<\/a> a une m\u00e9canique comparable \u00e0 celle de la chasse \u00e0 la sauvagine et aux oiseaux migrateurs, avec des cibles qui s'\u00e9loignent de plus en plus de la personne qui tire. Comme la vraie chasse, le tir \u00e0 la vol\u00e9e implique de suivre la trajectoire de cibles en mouvement avec son <a href=\"https:\/\/www.sail.ca\/fr\/chasse\/armes-a-feu\/fusils\" target=\"_blank\" rel=\"noopener\">fusil de chasse<\/a> puis de saisir le meilleur moment pour tirer. Vous devez ainsi pointer votre fusil vers le point de d\u00e9part du pigeon d'argile, puis suivre la trajectoire de celui-ci avec votre corps et votre arme \u00e0 feu, dans un mouvement fluide et en acc\u00e9l\u00e9rant l\u00e9g\u00e8rement au fur et \u00e0 mesure. Portez toujours attention \u00e0 votre position, \u00e0 votre posture et \u00e0 la mani\u00e8re dont vous placez vos pieds afin de conserver votre \u00e9quilibre.\r\n\r\nEn plus d\u2019\u00eatre un excellent entra\u00eenement pour la vis\u00e9e et le maniement d'arme \u00e0 feu, le tir au pigeon d'argile vous aidera \u00e0 d\u00e9velopper votre confiance et vous donnera l\u2019occasion de tester vos habilet\u00e9s, ce qui constitue une pr\u00e9paration hors pair pour la chasse. C'est aussi l'une des meilleures choses que vous pouvez faire pour maximiser vos chances de r\u00e9ussir de belles r\u00e9coltes."}],"author_type":"wordpress","partnership_options":{"partnership_label":"","partner_logo":null,"partner_link":"","partnership_text":""},"override_related_posts":false,"related_posts":null,"right_cta_visibility":false,"sidebar_cta_content_override":false,"sidebar_cta_title":"","sidebar_cta_description":"","sidebar_cta_button":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse | SAIL Blogue<\/title>\n<meta name=\"description\" content=\"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse\" \/>\n<meta property=\"og:description\" content=\"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIL Blogue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SAILpleinairoutdoors\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T19:03:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T18:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SAIL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SAIL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/\"},\"author\":{\"name\":\"SAIL\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\"},\"headline\":\"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse\",\"datePublished\":\"2024-03-24T19:03:50+00:00\",\"dateModified\":\"2024-03-25T18:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/09\\\/1-1.png\",\"keywords\":[\"F\u00e9d\u00e9CP\",\"Printemps\"],\"articleSection\":[\"Chasse\",\"Chasse aux oiseaux migrateurs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/\",\"name\":\"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse | SAIL Blogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/09\\\/1-1.png\",\"datePublished\":\"2024-03-24T19:03:50+00:00\",\"dateModified\":\"2024-03-25T18:39:40+00:00\",\"description\":\"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/09\\\/1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2021\\\/09\\\/1-1.png\",\"width\":1080,\"height\":720,\"caption\":\"Chasse \u00e0 l'oiseaux migrateurs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chasse\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chasse aux oiseaux migrateurs\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/chasse\\\/chasse-oiseaux-migrateurs\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"name\":\"SAIL Blogue\",\"description\":\"Blogue SAIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#organization\",\"name\":\"SAIL\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"width\":1200,\"height\":630,\"caption\":\"SAIL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAILpleinairoutdoors\",\"https:\\\/\\\/www.instagram.com\\\/sailpleinairoutdoors\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\\\/blog\",\"https:\\\/\\\/www.youtube.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.tiktok.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.pinterest.com\\\/sailpleinairoutdoors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/ec271341caea16ddcb7cc3b6a04133cf\",\"name\":\"SAIL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g\",\"caption\":\"SAIL\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse | SAIL Blogue","description":"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/","og_locale":"fr_CA","og_type":"article","og_title":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse","og_description":"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.","og_url":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/","og_site_name":"SAIL Blogue","article_publisher":"https:\/\/www.facebook.com\/SAILpleinairoutdoors","article_published_time":"2024-03-24T19:03:50+00:00","article_modified_time":"2024-03-25T18:39:40+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png","type":"image\/png"}],"author":"SAIL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"SAIL","Estimation du temps de lecture":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#article","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/"},"author":{"name":"SAIL","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf"},"headline":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse","datePublished":"2024-03-24T19:03:50+00:00","dateModified":"2024-03-25T18:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png","keywords":["F\u00e9d\u00e9CP","Printemps"],"articleSection":["Chasse","Chasse aux oiseaux migrateurs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/","url":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/","name":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse | SAIL Blogue","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#primaryimage"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png","datePublished":"2024-03-24T19:03:50+00:00","dateModified":"2024-03-25T18:39:40+00:00","description":"Apprenez-en plus sur la chasse aux oiseaux migrateurs et \u00e0 la sauvagine, une activit\u00e9 r\u00e9glement\u00e9e qui n\u00e9cessite une bonne pr\u00e9paration. Lisez l\u2019article.","breadcrumb":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#primaryimage","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2021\/09\/1-1.png","width":1080,"height":720,"caption":"Chasse \u00e0 l'oiseaux migrateurs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sail.ca\/blog\/fr\/chasse-aux-oiseaux-migrateurs-conseils-de-base-pour-bien-planifier-votre-prochaine-partie-de-chasse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sail.ca\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Chasse","item":"https:\/\/www.sail.ca\/blog\/fr\/chasse\/"},{"@type":"ListItem","position":3,"name":"Chasse aux oiseaux migrateurs","item":"https:\/\/www.sail.ca\/blog\/fr\/chasse\/chasse-oiseaux-migrateurs\/"},{"@type":"ListItem","position":4,"name":"Chasse aux oiseaux migrateurs : conseils de base pour bien planifier votre prochaine partie de chasse"}]},{"@type":"WebSite","@id":"https:\/\/www.sail.ca\/blog\/fr\/#website","url":"https:\/\/www.sail.ca\/blog\/fr\/","name":"SAIL Blogue","description":"Blogue SAIL","publisher":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sail.ca\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.sail.ca\/blog\/fr\/#organization","name":"SAIL","url":"https:\/\/www.sail.ca\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","width":1200,"height":630,"caption":"SAIL"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAILpleinairoutdoors","https:\/\/www.instagram.com\/sailpleinairoutdoors\/","https:\/\/www.linkedin.com\/company\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\/blog","https:\/\/www.youtube.com\/sailpleinairoutdoors","https:\/\/www.tiktok.com\/sailpleinairoutdoors","https:\/\/www.pinterest.com\/sailpleinairoutdoors\/"]},{"@type":"Person","@id":"https:\/\/www.sail.ca\/blog\/fr\/#\/schema\/person\/ec271341caea16ddcb7cc3b6a04133cf","name":"SAIL","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/555e9a08f123ac4486c2b7ec44d2de6ea847471983d99d7fc537ae551042e484?s=96&d=mm&r=g","caption":"SAIL"}}]}},"_links":{"self":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/comments?post=12271"}],"version-history":[{"count":6,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12271\/revisions"}],"predecessor-version":[{"id":20279,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/posts\/12271\/revisions\/20279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media\/20268"}],"wp:attachment":[{"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/media?parent=12271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/categories?post=12271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sail.ca\/blog\/fr\/wp-json\/wp\/v2\/tags?post=12271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}