{"id":1200,"count":1,"description":"","link":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/","name":"water repellent treatment","slug":"water-repellent-treatment","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>water repellent treatment | SAIL Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"water repellent treatment Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIL Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/tag\\\/water-repellent-treatment\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/tag\\\/water-repellent-treatment\\\/\",\"name\":\"water repellent treatment | SAIL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/tag\\\/water-repellent-treatment\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/tag\\\/water-repellent-treatment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"water repellent treatment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/\",\"name\":\"SAIL Blog\",\"description\":\"Blogue SAIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#organization\",\"name\":\"SAIL\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"contentUrl\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/app\\\/uploads\\\/2022\\\/06\\\/sail-default-og.png\",\"width\":1200,\"height\":630,\"caption\":\"SAIL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sail.ca\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAILpleinairoutdoors\",\"https:\\\/\\\/www.instagram.com\\\/sailpleinairoutdoors\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\\\/blog\",\"https:\\\/\\\/www.youtube.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.tiktok.com\\\/sailpleinairoutdoors\",\"https:\\\/\\\/www.pinterest.com\\\/sailpleinairoutdoors\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"water repellent treatment | SAIL Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"water repellent treatment Archives","og_url":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/","og_site_name":"SAIL Blog","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/","url":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/","name":"water repellent treatment | SAIL Blog","isPartOf":{"@id":"https:\/\/www.sail.ca\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sail.ca\/blog\/tag\/water-repellent-treatment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sail.ca\/blog\/"},{"@type":"ListItem","position":2,"name":"water repellent treatment"}]},{"@type":"WebSite","@id":"https:\/\/www.sail.ca\/blog\/#website","url":"https:\/\/www.sail.ca\/blog\/","name":"SAIL Blog","description":"Blogue SAIL","publisher":{"@id":"https:\/\/www.sail.ca\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sail.ca\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.sail.ca\/blog\/#organization","name":"SAIL","url":"https:\/\/www.sail.ca\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.sail.ca\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","contentUrl":"https:\/\/www.sail.ca\/blog\/app\/uploads\/2022\/06\/sail-default-og.png","width":1200,"height":630,"caption":"SAIL"},"image":{"@id":"https:\/\/www.sail.ca\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAILpleinairoutdoors","https:\/\/www.instagram.com\/sailpleinairoutdoors\/","https:\/\/www.linkedin.com\/company\/sailpleinairoutdoors?original_referer=httpswww.sail.ca\/blog","https:\/\/www.youtube.com\/sailpleinairoutdoors","https:\/\/www.tiktok.com\/sailpleinairoutdoors","https:\/\/www.pinterest.com\/sailpleinairoutdoors\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sail.ca\/blog\/wp-json\/wp\/v2\/tags\/1200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sail.ca\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sail.ca\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sail.ca\/blog\/wp-json\/wp\/v2\/posts?tags=1200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}